{"id":1038,"date":"2024-09-29T11:55:24","date_gmt":"2024-09-29T11:55:24","guid":{"rendered":"https:\/\/bbpmpjateng.kemendikdasmen.go.id\/ppid\/?page_id=1038"},"modified":"2025-10-16T07:20:33","modified_gmt":"2025-10-16T07:20:33","slug":"program-kegiatan","status":"publish","type":"page","link":"https:\/\/bbpmpjateng.kemendikdasmen.go.id\/ppid\/informasi-berkala\/program-kegiatan\/","title":{"rendered":"Program Kegiatan"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-cc6471b1 wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-border-color has-tertiary-border-color\"><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">No<\/th><th>Nama Dokumen<\/th><th class=\"has-text-align-center\" data-align=\"center\">Tahun<\/th><th class=\"has-text-align-center\" data-align=\"center\">Jenis<\/th><th class=\"has-text-align-center\" data-align=\"center\">Aksi<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td>Program Kegiatan<\/td><td class=\"has-text-align-center\" data-align=\"center\">2023<\/td><td class=\"has-text-align-center\" data-align=\"center\">Periodik<\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/bbpmpjateng.kemendikdasmen.go.id\/ppid\/wp-content\/uploads\/2023\/09\/Program-dan-kegiatan-BBPMP-Jateng-2023.pdf\">Unduh<\/a><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><td>Agenda Penting<\/td><td class=\"has-text-align-center\" data-align=\"center\">2023<\/td><td class=\"has-text-align-center\" data-align=\"center\">Periodik<\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/bbpmpjateng.kemendikdasmen.go.id\/ppid\/wp-content\/uploads\/2023\/09\/Agenda-Penting-2023.pdf\">Unduh<\/a><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">3<\/td><td>Program Kegiatan<\/td><td class=\"has-text-align-center\" data-align=\"center\">2024<\/td><td class=\"has-text-align-center\" data-align=\"center\">Periodik<\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/bbpmpjateng.kemendikdasmen.go.id\/ppid\/wp-content\/uploads\/2024\/11\/Informasi-Program-dan-Kegiatan-BBPMP-Jawa-Tengah-2024.xlsx\">Unduh<\/a><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><td>Agenda Penting<\/td><td class=\"has-text-align-center\" data-align=\"center\">2024<\/td><td class=\"has-text-align-center\" data-align=\"center\">Periodik<\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/bbpmpjateng.kemendikdasmen.go.id\/ppid\/agenda-penting-2024\/\">Lihat<\/a>\/<a href=\"https:\/\/bbpmpjateng.kemendikdasmen.go.id\/ppid\/wp-content\/uploads\/2024\/11\/AGENDA-PENTING-2024.xlsx\">Unduh<\/a><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">5<\/td><td>Program Kegiatan<\/td><td class=\"has-text-align-center\" data-align=\"center\">2025<\/td><td class=\"has-text-align-center\" data-align=\"center\">Periodik<\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/bbpmpjateng.kemendikdasmen.go.id\/ppid\/wp-content\/uploads\/2025\/10\/Program-Kegiatan-2025.pdf\">Unduh<\/a><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">6<\/td><td>Agenda Penting<\/td><td class=\"has-text-align-center\" data-align=\"center\">2025<\/td><td class=\"has-text-align-center\" data-align=\"center\">Periodik<\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/bbpmpjateng.kemendikdasmen.go.id\/ppid\/agenda-penting-2025\/\">Lihat<\/a>\/<a href=\"https:\/\/bbpmpjateng.kemendikdasmen.go.id\/ppid\/wp-content\/uploads\/2025\/10\/Agenda-2025.pdf\">Unduh<\/a><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">7<\/td><td>Rencana Anggaran<\/td><td class=\"has-text-align-center\" data-align=\"center\">2025<\/td><td class=\"has-text-align-center\" data-align=\"center\">Periodik<\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/bbpmpjateng.kemendikdasmen.go.id\/ppid\/wp-content\/uploads\/2025\/10\/RINCIAN-KERTAS-KERJA-SATKER-POK-2025.pdf\">Unduh<\/a><\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-cc6471b1 wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-border-color has-tertiary-border-color\"><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">No<\/th><th>Nama Dokumen<\/th><th>Bulan<\/th><th class=\"has-text-align-center\" data-align=\"center\">Tahun<\/th><th class=\"has-text-align-center\" data-align=\"center\">Jenis<\/th><th class=\"has-text-align-center\" data-align=\"center\">Aksi<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td>Jadwal Kegiatan<\/td><td>Januari<\/td><td class=\"has-text-align-center\" data-align=\"center\">2025<\/td><td class=\"has-text-align-center\" data-align=\"center\">Periodik<\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/bbpmpjateng.kemendikdasmen.go.id\/ppid\/wp-content\/uploads\/2025\/10\/Jadwal-Kegiatan-Januari.pdf\">Unduh<\/a><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><td>Jadwal Kegiatan<\/td><td>Februari<\/td><td class=\"has-text-align-center\" data-align=\"center\">2025<\/td><td class=\"has-text-align-center\" data-align=\"center\">Periodik<\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/bbpmpjateng.kemendikdasmen.go.id\/ppid\/wp-content\/uploads\/2025\/10\/Jadwal-Kegiatan-Februari.pdf\">Unduh<\/a><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">3<\/td><td>Jadwal Kegiatan<\/td><td>Maret<\/td><td class=\"has-text-align-center\" data-align=\"center\">2025<\/td><td class=\"has-text-align-center\" data-align=\"center\">Periodik<\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/bbpmpjateng.kemendikdasmen.go.id\/ppid\/wp-content\/uploads\/2025\/10\/Jadwal-Kegiatan-Maret.pdf\">Unduh<\/a><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><td>Jadwal Kegiatan<\/td><td>April<\/td><td class=\"has-text-align-center\" data-align=\"center\">2025<\/td><td class=\"has-text-align-center\" data-align=\"center\">Periodik<\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/bbpmpjateng.kemendikdasmen.go.id\/ppid\/wp-content\/uploads\/2025\/10\/Jadwal-Kegiatan-April.pdf\">Unduh<\/a><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">5<\/td><td>Jadwal Kegiatan<\/td><td>Mei<\/td><td class=\"has-text-align-center\" data-align=\"center\">2025<\/td><td class=\"has-text-align-center\" data-align=\"center\">Periodik<\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/bbpmpjateng.kemendikdasmen.go.id\/ppid\/wp-content\/uploads\/2025\/10\/Jadwal-Kegiatan-Mei.pdf\">Unduh<\/a><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">6<\/td><td>Jadwal Kegiatan<\/td><td>Juni<\/td><td class=\"has-text-align-center\" data-align=\"center\">2025<\/td><td class=\"has-text-align-center\" data-align=\"center\">Periodik<\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/bbpmpjateng.kemendikdasmen.go.id\/ppid\/wp-content\/uploads\/2025\/10\/Jadwal-Kegiatan-Juni.pdf\">Unduh<\/a><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">7<\/td><td>Jadwal Kegiatan<\/td><td>Juli<\/td><td class=\"has-text-align-center\" data-align=\"center\">2025<\/td><td class=\"has-text-align-center\" data-align=\"center\">Periodik<\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/bbpmpjateng.kemendikdasmen.go.id\/ppid\/wp-content\/uploads\/2025\/10\/Jadwal-Kegiatan-Juli.pdf\">Unduh<\/a><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">8<\/td><td>Jadwal Kegiatan<\/td><td>Agustus<\/td><td class=\"has-text-align-center\" data-align=\"center\">2025<\/td><td class=\"has-text-align-center\" data-align=\"center\">Periodik<\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/bbpmpjateng.kemendikdasmen.go.id\/ppid\/wp-content\/uploads\/2025\/10\/Jadwal-Kegiatan-Agustus.pdf\">Unduh<\/a><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">9<\/td><td>Jadwal Kegiatan<\/td><td>September<\/td><td class=\"has-text-align-center\" data-align=\"center\">2025<\/td><td class=\"has-text-align-center\" data-align=\"center\">Periodik<\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/bbpmpjateng.kemendikdasmen.go.id\/ppid\/wp-content\/uploads\/2025\/10\/Jadwal-Kegiatan-September.pdf\">Unduh<\/a><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">10<\/td><td>Jadwal Kegiatan<\/td><td>Oktober<\/td><td class=\"has-text-align-center\" data-align=\"center\">2025<\/td><td class=\"has-text-align-center\" data-align=\"center\">Periodik<\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/bbpmpjateng.kemendikdasmen.go.id\/ppid\/wp-content\/uploads\/2025\/10\/Jadwal-Kegiatan-Oktober.pdf\">Unduh<\/a><\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>No Nama Dokumen Tahun Jenis Aksi 1 Program Kegiatan 2023 Periodik Unduh 2 Agenda Penting 2023 Periodik Unduh 3 Program Kegiatan 2024 Periodik Unduh 4 Agenda Penting 2024 Periodik Lihat\/Unduh 5 Program Kegiatan 2025 Periodik Unduh 6 Agenda Penting 2025 Periodik Lihat\/Unduh 7 Rencana Anggaran 2025 Periodik Unduh No Nama Dokumen Bulan Tahun Jenis Aksi&#8230;<\/p>\n","protected":false},"author":1,"featured_media":570,"parent":314,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"wp-custom-template-without-feature-image","meta":{"footnotes":""},"class_list":["post-1038","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/bbpmpjateng.kemendikdasmen.go.id\/ppid\/wp-json\/wp\/v2\/pages\/1038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bbpmpjateng.kemendikdasmen.go.id\/ppid\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bbpmpjateng.kemendikdasmen.go.id\/ppid\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bbpmpjateng.kemendikdasmen.go.id\/ppid\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bbpmpjateng.kemendikdasmen.go.id\/ppid\/wp-json\/wp\/v2\/comments?post=1038"}],"version-history":[{"count":28,"href":"https:\/\/bbpmpjateng.kemendikdasmen.go.id\/ppid\/wp-json\/wp\/v2\/pages\/1038\/revisions"}],"predecessor-version":[{"id":1791,"href":"https:\/\/bbpmpjateng.kemendikdasmen.go.id\/ppid\/wp-json\/wp\/v2\/pages\/1038\/revisions\/1791"}],"up":[{"embeddable":true,"href":"https:\/\/bbpmpjateng.kemendikdasmen.go.id\/ppid\/wp-json\/wp\/v2\/pages\/314"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bbpmpjateng.kemendikdasmen.go.id\/ppid\/wp-json\/wp\/v2\/media\/570"}],"wp:attachment":[{"href":"https:\/\/bbpmpjateng.kemendikdasmen.go.id\/ppid\/wp-json\/wp\/v2\/media?parent=1038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}